{"id":313749,"date":"2025-04-22T12:37:43","date_gmt":"2025-04-22T05:37:43","guid":{"rendered":"https:\/\/imse.kmitl.ac.th\/?page_id=313749"},"modified":"2026-04-16T09:21:19","modified_gmt":"2026-04-16T02:21:19","slug":"home2025","status":"publish","type":"page","link":"https:\/\/imse.kmitl.ac.th\/th\/","title":{"rendered":"HOME2025"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"313749\" class=\"elementor elementor-313749\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b633208 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"b633208\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-29c2d1c\" data-id=\"29c2d1c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f74e293 elementor--v-position-bottom elementor-widget__width-initial elementor--h-position-center elementor-arrows-position-inside elementor-pagination-position-inside elementor-widget elementor-widget-slides\" data-id=\"f74e293\" data-element_type=\"widget\" data-settings=\"{&quot;autoplay_speed&quot;:5004,&quot;transition_speed&quot;:1000,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"\" dir=\"ltr\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-b07f118 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div  class=\"elementor-button elementor-slide-button elementor-size-sm\">Click Here<\/div><\/div><\/div><\/div><div class=\"elementor-repeater-item-cf9264a swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div  class=\"elementor-button elementor-slide-button elementor-size-sm\">Click Here<\/div><\/div><\/div><\/div><div class=\"elementor-repeater-item-43b48af swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><a class=\"swiper-slide-inner\" href=\"https:\/\/imse.kmitl.ac.th\/313607\/no-gift-policy\/\"><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">No Gift Policy<\/div><div  class=\"elementor-button elementor-slide-button elementor-size-sm\">Click Here<\/div><\/div><\/a><\/div><div class=\"elementor-repeater-item-cc361fe swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><a class=\"swiper-slide-inner\" href=\"https:\/\/www.facebook.com\/shifterth\/videos\/1996454210487189\"><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">\u0e2a\u0e31\u0e21\u0e20\u0e32\u0e29\u0e13\u0e4c\u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e02\u0e08\u0e23\u0e28\u0e31\u0e01\u0e14\u0e34\u0e4c<\/div><div class=\"elementor-slide-description\">City of Noise \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e02\u0e2d\u0e25\u0e14\u0e40\u0e2a\u0e35\u0e22\u0e07 Noise<\/div><div  class=\"elementor-button elementor-slide-button elementor-size-sm\">Click Here<\/div><\/div><\/a><\/div><div class=\"elementor-repeater-item-9b806a5 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"elementor-background-overlay\"><\/div><a class=\"swiper-slide-inner\" href=\"https:\/\/theurbanis.com\/life\/2020\/01\/15\/2828\/\"><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">\u2018\u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e02\u0e08\u0e23\u0e28\u0e31\u0e01\u0e14\u0e34\u0e4c \u0e01\u0e34\u0e15\u0e15\u0e34\u0e40\u0e21\u0e18\u0e32\u0e27\u0e35\u0e19\u0e31\u0e19\u0e17\u0e4c\u2019 <\/div><div class=\"elementor-slide-description\">\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e43\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07 : \u0e04\u0e19\u0e44\u0e17\u0e22\u0e04\u0e38\u0e49\u0e19\u0e40\u0e04\u0e22\u0e01\u0e31\u0e1a\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e14\u0e31\u0e07\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e31\u0e19\u0e15\u0e23\u0e32\u0e22\u0e21\u0e32\u0e01\u0e40\u0e01\u0e34\u0e19\u0e44\u0e1b\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e1b\u0e25\u0e48\u0e32<\/div><div  class=\"elementor-button elementor-slide-button elementor-size-sm\">Click Here<\/div><\/div><\/a><\/div><div class=\"elementor-repeater-item-9f4c077 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><a class=\"swiper-slide-inner\" href=\"https:\/\/imse.kmitl.ac.th\/th\/pr-master-degree\/\"><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23 \u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15\u0e28\u0e36\u0e01\u0e29\u0e32<\/div><div  class=\"elementor-button elementor-slide-button elementor-size-sm\">Click here<\/div><\/div><\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Previous slide\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Next slide\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d8afc08 elementor-section-height-min-height elementor-section-items-stretch elementor-section-full_width elementor-section-height-default\" data-id=\"d8afc08\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;10d7102&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:null,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}]}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4e899e2\" data-id=\"4e899e2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-50307c4 uael-heading-align-center elementor-widget elementor-widget-uael-advanced-heading\" data-id=\"50307c4\" data-element_type=\"widget\" data-widget_type=\"uael-advanced-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"uael-module-content uael-heading-wrapper\">\n\t\t\t\t\t\t\n\t\t\t<h6 class=\"uael-heading\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-heading-text elementor-inline-editing uael-size--default\" data-elementor-setting-key=\"heading_title\" data-elementor-inline-editing-toolbar=\"basic\">IMSE Events<\/span>\n\t\t\t\t\t\t\t<\/h6>\n\n\t\t\t\t\t\t\t<div class=\"uael-sub-heading elementor-inline-editing\" data-elementor-setting-key=\"sub_heading\" data-elementor-inline-editing-toolbar=\"advanced\" >\u0e02\u0e48\u0e32\u0e27\u0e2a\u0e32\u0e23\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0c504af uael-post__link-complete-yes uael-posts-thumbnail-ratio elementor-widget elementor-widget-uael-posts\" data-id=\"0c504af\" data-element_type=\"widget\" data-settings=\"{&quot;event_slides_to_show&quot;:3,&quot;event_slides_to_show_tablet&quot;:2,&quot;event_slides_to_show_mobile&quot;:1}\" data-widget_type=\"uael-posts.event\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"uael-post__header\">\n\t\t\t\t\t<\/div>\n\t\t<div class=\"uael-post__body\">\n\t\t\t\n\t\t\n\t\t<div class=\"uael-post-grid uael-posts\" data-query-type=\"custom\" data-structure=\"masonry\" data-layout=\"masonry\" data-page=\"313749\" data-skin=\"event\" data-filter-default=\"\" data-offset-top=\"30\" >\n\n\t\t\t\t\t\t\t<div class=\"uael-post-grid__inner uael-post__columns-3 uael-post__columns-tablet-2 uael-post__columns-mobile-1 uael-post-masonry\">\n\t\t\t\n\n<div class=\"uael-post-wrapper   event news \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2b\u0e25\u0e31\u0e01 \">\n\t<div class=\"uael-post__bg-wrap uael-bg-wrap-disabled\">\n\n\t\t\t\t\t<a href=\"https:\/\/imse.kmitl.ac.th\/th\/314884\/\" target=\"_self\" class=\"uael-post__complete-box-overlay\" aria-label=\"Link Complete Box\"><\/a>\n\t\t\t\t\n\t\t<div class=\"uael-post__inner-wrap uael-inner-wrap-disabled\">\n\n\t\t\t\t<div class=\"uael-post__thumbnail \">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"720\" height=\"720\" src=\"https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2026\/05\/696588678_1458360029636790_4463462866560711166_n.jpg\" class=\"attachment-full size-full wp-image-314883\" alt=\"\" srcset=\"https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2026\/05\/696588678_1458360029636790_4463462866560711166_n.jpg 720w, https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2026\/05\/696588678_1458360029636790_4463462866560711166_n-300x300.jpg 300w, https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2026\/05\/696588678_1458360029636790_4463462866560711166_n-150x150.jpg 150w, https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2026\/05\/696588678_1458360029636790_4463462866560711166_n-12x12.jpg 12w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/>\t\t\t\t\t<div class=\"uael-post__datebox \">\n\t\t\t\t<div class=\"uael-post__date-wrap\">\n\t\t\t\t\t\t\t\t\t\t<span class='uael-post__date-month'>\u0e1e.\u0e04.<\/span><span class='uael-post__date-day'>13<\/span>\t\t\t\t<\/div>\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n\t\t\t\n\t\t\t<div class=\"uael-post__content-wrap uael-content-wrap-disabled\">\n\n\t\t\t\t\t<h4 class=\"uael-post__title\">\n\n\t\t\n\t\t\t\t\t\t<a href=\"https:\/\/imse.kmitl.ac.th\/th\/314884\/\" target=\"_self\">\n\t\t\t\t\u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e43\u0e19 IMSE\n4 \u0e1b\u0e35 \u0e40\u0e23\u0e35\u0e22\u0e19\u0e2d\u0e30\u0e44\u0e23\u0e1a\u0e49\u0e32\u0e07? \ud83d\udc40\n\n\u0e2b\u0e25\u0e32\u0e22\u0e04\u0e19\u0e2a\u0e07\u0e2a\u0e31\u0e22\u0e27\u0e48\u0e32\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e41\u0e25\u0e49\u0e27\u0e08\u0e30\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2d\u0e30\u0e44\u0e23 \u0e1a\u0e2d\u0e01\u0e40\u0e25\u0e22\u0e27\u0e48\u0e32\u0e17\u0e35\u0e48\u0e19\u0e35\u0e48\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e21\u0e35\u0e41\u0e04\u0e48\u0e17\u0e32\u0e07\u0e40\u0e14\u0e35\u0e22\u0e27 \ud83c\udfaf\n\n\u0e17\u0e35\u0e48 IMSE \u0e21\u0e35 3 \u0e41\u0e02\u0e19\u0e07\u0e43\u0e2b\u0e49\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e15\u0e32\t\t\t<\/a>\n\n\t\t\t\t<\/h4>\n\t\t\n\t\t<div class=\"uael-post__excerpt\">\n\t\t\t\u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e43\u0e19 IMSE 4 \u0e1b\u0e35 \u0e40\u0e23\u0e35\u0e22\u0e19\u0e2d\u0e30\u0e44\u0e23\u0e1a\u0e49\u0e32\u0e07? \ud83d\udc40 \u0e2b\u0e25\u0e32\u0e22\u0e04\u0e19\u0e2a\u0e07\u0e2a\u0e31\u0e22\u0e27\u0e48\u0e32\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e41\u0e25\u0e49\u0e27\u0e08\u0e30\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2d\u0e30\u0e44\u0e23 \u0e1a\u0e2d\u0e01\u0e40\u0e25\u0e22\u0e27\u0e48\u0e32\u0e17\u0e35\u0e48\u0e19\u0e35\u0e48\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e21\u0e35\u0e41\u0e04\u0e48\u0e17\u0e32\u0e07\u0e40\u0e14\u0e35\u0e22\u0e27 \ud83c\udfaf \u0e17\u0e35\u0e48 IMSE \u0e21\u0e35 3 \u0e41\u0e02\u0e19\u0e07\u0e43\u0e2b\u0e49\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e15\u0e32\u0e21\u0e2a\u0e32\u0e22\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e48\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e04\u0e38\u0e13 \ud83c\udf93 \ud83c\udfa7 Audio ...\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\n\n\t<\/div>\n\n<\/div>\n\n\n<div class=\"uael-post-wrapper   event news \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2b\u0e25\u0e31\u0e01 \">\n\t<div class=\"uael-post__bg-wrap uael-bg-wrap-disabled\">\n\n\t\t\t\t\t<a href=\"https:\/\/imse.kmitl.ac.th\/th\/314870\/\" target=\"_self\" class=\"uael-post__complete-box-overlay\" aria-label=\"Link Complete Box\"><\/a>\n\t\t\t\t\n\t\t<div class=\"uael-post__inner-wrap uael-inner-wrap-disabled\">\n\n\t\t\t\t<div class=\"uael-post__thumbnail \">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1280\" height=\"720\" src=\"https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2026\/05\/695536701_1453533683452758_5012916895820910949_n.jpg\" class=\"attachment-full size-full wp-image-314869\" alt=\"\" srcset=\"https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2026\/05\/695536701_1453533683452758_5012916895820910949_n.jpg 1280w, https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2026\/05\/695536701_1453533683452758_5012916895820910949_n-300x169.jpg 300w, https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2026\/05\/695536701_1453533683452758_5012916895820910949_n-1024x576.jpg 1024w, https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2026\/05\/695536701_1453533683452758_5012916895820910949_n-768x432.jpg 768w, https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2026\/05\/695536701_1453533683452758_5012916895820910949_n-18x10.jpg 18w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>\t\t\t\t\t<div class=\"uael-post__datebox \">\n\t\t\t\t<div class=\"uael-post__date-wrap\">\n\t\t\t\t\t\t\t\t\t\t<span class='uael-post__date-month'>\u0e1e.\u0e04.<\/span><span class='uael-post__date-day'>07<\/span>\t\t\t\t<\/div>\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n\t\t\t\n\t\t\t<div class=\"uael-post__content-wrap uael-content-wrap-disabled\">\n\n\t\t\t\t\t<h4 class=\"uael-post__title\">\n\n\t\t\n\t\t\t\t\t\t<a href=\"https:\/\/imse.kmitl.ac.th\/th\/314870\/\" target=\"_self\">\n\t\t\t\t\u0e02\u0e2d\u0e2d\u0e20\u0e31\u0e22\u0e43\u0e19\u0e04\u0e27\u0e32\u0e21\u0e44\u0e21\u0e48\u0e2a\u0e30\u0e14\u0e27\u0e01\ud83d\ude4f\n#IMSE  #KMITL\t\t\t<\/a>\n\n\t\t\t\t<\/h4>\n\t\t\n\t\t<div class=\"uael-post__excerpt\">\n\t\t\t\u0e02\u0e2d\u0e2d\u0e20\u0e31\u0e22\u0e43\u0e19\u0e04\u0e27\u0e32\u0e21\u0e44\u0e21\u0e48\u0e2a\u0e30\u0e14\u0e27\u0e01\ud83d\ude4f #IMSE #KMITL\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\n\n\t<\/div>\n\n<\/div>\n\n\n<div class=\"uael-post-wrapper   event news \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2b\u0e25\u0e31\u0e01 \">\n\t<div class=\"uael-post__bg-wrap uael-bg-wrap-disabled\">\n\n\t\t\t\t\t<a href=\"https:\/\/imse.kmitl.ac.th\/th\/314859\/\" target=\"_self\" class=\"uael-post__complete-box-overlay\" aria-label=\"Link Complete Box\"><\/a>\n\t\t\t\t\n\t\t<div class=\"uael-post__inner-wrap uael-inner-wrap-disabled\">\n\n\t\t\t\t<div class=\"uael-post__thumbnail \">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"720\" height=\"720\" src=\"https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2026\/05\/690128755_1451550386984421_578924563119446962_n.jpg\" class=\"attachment-full size-full wp-image-314858\" alt=\"\" srcset=\"https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2026\/05\/690128755_1451550386984421_578924563119446962_n.jpg 720w, https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2026\/05\/690128755_1451550386984421_578924563119446962_n-300x300.jpg 300w, https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2026\/05\/690128755_1451550386984421_578924563119446962_n-150x150.jpg 150w, https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2026\/05\/690128755_1451550386984421_578924563119446962_n-12x12.jpg 12w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/>\t\t\t\t\t<div class=\"uael-post__datebox \">\n\t\t\t\t<div class=\"uael-post__date-wrap\">\n\t\t\t\t\t\t\t\t\t\t<span class='uael-post__date-month'>\u0e1e.\u0e04.<\/span><span class='uael-post__date-day'>05<\/span>\t\t\t\t<\/div>\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n\t\t\t\n\t\t\t<div class=\"uael-post__content-wrap uael-content-wrap-disabled\">\n\n\t\t\t\t\t<h4 class=\"uael-post__title\">\n\n\t\t\n\t\t\t\t\t\t<a href=\"https:\/\/imse.kmitl.ac.th\/th\/314859\/\" target=\"_self\">\n\t\t\t\t\u0e17\u0e23\u0e07\u0e1e\u0e23\u0e30\u0e40\u0e08\u0e23\u0e34\u0e0d\n\u0e55 \u0e1e\u0e24\u0e29\u0e20\u0e32\u0e04\u0e21\n\u0e27\u0e31\u0e19\u0e04\u0e25\u0e49\u0e32\u0e22\u0e27\u0e31\u0e19\u0e1b\u0e23\u0e30\u0e2a\u0e39\u0e15\u0e34\n\u0e1e\u0e23\u0e30\u0e40\u0e08\u0e49\u0e32\u0e27\u0e23\u0e27\u0e07\u0e28\u0e4c\u0e40\u0e18\u0e2d \u0e1e\u0e23\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e40\u0e08\u0e49\u0e32\u0e2d\u0e17\u0e34\u0e15\u0e22\u0e32\u0e17\u0e23\u0e01\u0e34\u0e15\u0e34\u0e04\u0e38\u0e13\n\u0e04\u0e27\u0e23\u0e21\u0e34\u0e04\u0e27\u0e23\u0e41\u0e25\u0e49\u0e27\u0e41\u0e15\u0e48\u0e08\u0e30\u0e42\u0e1b\u0e23\u0e14\n\u0e40\u0e01\u0e25\u0e49\u0e32\u0e01\u0e23\u0e30\u0e2b\u0e21\u0e48\u0e2d\u0e21 \u0e04\u0e13\u0e30\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e04\u0e13\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\t\t\t<\/a>\n\n\t\t\t\t<\/h4>\n\t\t\n\t\t<div class=\"uael-post__excerpt\">\n\t\t\t\u0e17\u0e23\u0e07\u0e1e\u0e23\u0e30\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e55 \u0e1e\u0e24\u0e29\u0e20\u0e32\u0e04\u0e21 \u0e27\u0e31\u0e19\u0e04\u0e25\u0e49\u0e32\u0e22\u0e27\u0e31\u0e19\u0e1b\u0e23\u0e30\u0e2a\u0e39\u0e15\u0e34 \u0e1e\u0e23\u0e30\u0e40\u0e08\u0e49\u0e32\u0e27\u0e23\u0e27\u0e07\u0e28\u0e4c\u0e40\u0e18\u0e2d \u0e1e\u0e23\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e40\u0e08\u0e49\u0e32\u0e2d\u0e17\u0e34\u0e15\u0e22\u0e32\u0e17\u0e23\u0e01\u0e34\u0e15\u0e34\u0e04\u0e38\u0e13 \u0e04\u0e27\u0e23\u0e21\u0e34\u0e04\u0e27\u0e23\u0e41\u0e25\u0e49\u0e27\u0e41\u0e15\u0e48\u0e08\u0e30\u0e42\u0e1b\u0e23\u0e14 \u0e40\u0e01\u0e25\u0e49\u0e32\u0e01\u0e23\u0e30\u0e2b\u0e21\u0e48\u0e2d\u0e21 \u0e04\u0e13\u0e30\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e04\u0e13\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23 \u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e28\u0e34\u0e29\u0e22\u0e4c\u0e40\u0e01\u0e48\u0e32 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e31\u0e07\u0e04\u0e35\u0e15 \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e1e\u0e23\u0e30\u0e08\u0e2d\u0e21\u0e40\u0e01\u0e25\u0e49\u0e32\u0e40\u0e08\u0e49\u0e32\u0e04\u0e38\u0e13\u0e17\u0e2b\u0e32\u0e23\u0e25\u0e32\u0e14\u0e01\u0e23\u0e30\u0e1a\u0e31\u0e07\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\n\n\t<\/div>\n\n<\/div>\n\n\n<div class=\"uael-post-wrapper   event news \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2b\u0e25\u0e31\u0e01 \">\n\t<div class=\"uael-post__bg-wrap uael-bg-wrap-disabled\">\n\n\t\t\t\t\t<a href=\"https:\/\/imse.kmitl.ac.th\/th\/314857\/\" target=\"_self\" class=\"uael-post__complete-box-overlay\" aria-label=\"Link Complete Box\"><\/a>\n\t\t\t\t\n\t\t<div class=\"uael-post__inner-wrap uael-inner-wrap-disabled\">\n\n\t\t\t\t<div class=\"uael-post__thumbnail \">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1920\" src=\"https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2026\/05\/687924091_27800084659580029_4160118339138478514_n.jpg\" class=\"attachment-full size-full wp-image-314856\" alt=\"\" srcset=\"https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2026\/05\/687924091_27800084659580029_4160118339138478514_n.jpg 1080w, https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2026\/05\/687924091_27800084659580029_4160118339138478514_n-169x300.jpg 169w, https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2026\/05\/687924091_27800084659580029_4160118339138478514_n-576x1024.jpg 576w, https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2026\/05\/687924091_27800084659580029_4160118339138478514_n-768x1365.jpg 768w, https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2026\/05\/687924091_27800084659580029_4160118339138478514_n-864x1536.jpg 864w, https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2026\/05\/687924091_27800084659580029_4160118339138478514_n-7x12.jpg 7w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/>\t\t\t\t\t<div class=\"uael-post__datebox \">\n\t\t\t\t<div class=\"uael-post__date-wrap\">\n\t\t\t\t\t\t\t\t\t\t<span class='uael-post__date-month'>\u0e1e.\u0e04.<\/span><span class='uael-post__date-day'>04<\/span>\t\t\t\t<\/div>\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n\t\t\t\n\t\t\t<div class=\"uael-post__content-wrap uael-content-wrap-disabled\">\n\n\t\t\t\t\t<h4 class=\"uael-post__title\">\n\n\t\t\n\t\t\t\t\t\t<a href=\"https:\/\/imse.kmitl.ac.th\/th\/314857\/\" target=\"_self\">\n\t\t\t\tTCAS \u0e23\u0e2d\u0e1a Admission \n\u0e08\u0e31\u0e14\u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a\u0e22\u0e31\u0e07\u0e44\u0e07\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e15\u0e34\u0e14\u0e21\u0e32\u0e01\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14? \ud83c\udfaf\n\n\u0e19\u0e49\u0e2d\u0e07\u0e46 \u0e23\u0e39\u0e49\u0e08\u0e31\u0e01\u0e23\u0e30\u0e1a\u0e1a\u0e19\u0e35\u0e49\u0e14\u0e35\u0e1e\u0e2d\u0e41\u0e25\u0e49\u0e27\u0e22\u0e31\u0e07? \ud83d\udc40 \u0e21\u0e32\u0e40\u0e0a\u0e47\u0e01\u0e43\u0e2b\u0e49\u0e0a\u0e31\u0e27\u0e23\u0e4c\u0e01\u0e48\u0e2d\u0e19\u0e01\u0e14\u0e2a\u0e48\u0e07\u0e01\u0e31\u0e19 \u0e40\u0e25\u0e37\u0e2d\u0e01\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14 10 \u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a \u0e41\t\t\t<\/a>\n\n\t\t\t\t<\/h4>\n\t\t\n\t\t<div class=\"uael-post__excerpt\">\n\t\t\tTCAS \u0e23\u0e2d\u0e1a Admission \u0e08\u0e31\u0e14\u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a\u0e22\u0e31\u0e07\u0e44\u0e07\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e15\u0e34\u0e14\u0e21\u0e32\u0e01\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14? \ud83c\udfaf \u0e19\u0e49\u0e2d\u0e07\u0e46 \u0e23\u0e39\u0e49\u0e08\u0e31\u0e01\u0e23\u0e30\u0e1a\u0e1a\u0e19\u0e35\u0e49\u0e14\u0e35\u0e1e\u0e2d\u0e41\u0e25\u0e49\u0e27\u0e22\u0e31\u0e07? \ud83d\udc40 \u0e21\u0e32\u0e40\u0e0a\u0e47\u0e01\u0e43\u0e2b\u0e49\u0e0a\u0e31\u0e27\u0e23\u0e4c\u0e01\u0e48\u0e2d\u0e19\u0e01\u0e14\u0e2a\u0e48\u0e07\u0e01\u0e31\u0e19 \u0e40\u0e25\u0e37\u0e2d\u0e01\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14 10 \u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a \u0e41\u0e15\u0e48\u0e15\u0e34\u0e14\u0e44\u0e14\u0e49\u0e41\u0e04\u0e48\u0e17\u0e35\u0e48\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e08\u0e30\u0e44\u0e25\u0e48\u0e08\u0e32\u0e01\u0e1a\u0e19\u0e25\u0e07\u0e25\u0e48\u0e32\u0e07\u0e40\u0e25\u0e22\u0e19\u0e30 \ud83d\udccb \u0e02\u0e2d\u0e41\u0e19\u0e30\u0e19\u0e33\u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e15\u0e32\u0e21\u0e19\u0e35\u0e49\u0e40\u0e25\u0e22 \ud83d\udc47 ...\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\n\n\t<\/div>\n\n<\/div>\n\n\n<div class=\"uael-post-wrapper   event news \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2b\u0e25\u0e31\u0e01 \">\n\t<div class=\"uael-post__bg-wrap uael-bg-wrap-disabled\">\n\n\t\t\t\t\t<a href=\"https:\/\/imse.kmitl.ac.th\/th\/314855\/\" target=\"_self\" class=\"uael-post__complete-box-overlay\" aria-label=\"Link Complete Box\"><\/a>\n\t\t\t\t\n\t\t<div class=\"uael-post__inner-wrap uael-inner-wrap-disabled\">\n\n\t\t\t\t<div class=\"uael-post__thumbnail \">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1920\" src=\"https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2026\/05\/682664637_4338955669693224_2827702057543468072_n.jpg\" class=\"attachment-full size-full wp-image-314854\" alt=\"\" srcset=\"https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2026\/05\/682664637_4338955669693224_2827702057543468072_n.jpg 1080w, https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2026\/05\/682664637_4338955669693224_2827702057543468072_n-169x300.jpg 169w, https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2026\/05\/682664637_4338955669693224_2827702057543468072_n-576x1024.jpg 576w, https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2026\/05\/682664637_4338955669693224_2827702057543468072_n-768x1365.jpg 768w, https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2026\/05\/682664637_4338955669693224_2827702057543468072_n-864x1536.jpg 864w, https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2026\/05\/682664637_4338955669693224_2827702057543468072_n-7x12.jpg 7w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/>\t\t\t\t\t<div class=\"uael-post__datebox \">\n\t\t\t\t<div class=\"uael-post__date-wrap\">\n\t\t\t\t\t\t\t\t\t\t<span class='uael-post__date-month'>\u0e1e.\u0e04.<\/span><span class='uael-post__date-day'>01<\/span>\t\t\t\t<\/div>\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n\t\t\t\n\t\t\t<div class=\"uael-post__content-wrap uael-content-wrap-disabled\">\n\n\t\t\t\t\t<h4 class=\"uael-post__title\">\n\n\t\t\n\t\t\t\t\t\t<a href=\"https:\/\/imse.kmitl.ac.th\/th\/314855\/\" target=\"_self\">\n\t\t\t\t\u0e27\u0e31\u0e19\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1b\u0e35\u0e19\u0e35\u0e49 \ud83c\udf89\n\u0e25\u0e2d\u0e07\u0e16\u0e32\u0e21\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07\u0e27\u0e48\u0e32 &#8220;\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e48&#8221;  \u0e04\u0e37\u0e2d\u0e2d\u0e30\u0e44\u0e23?\n\n\u0e23\u0e39\u0e49\u0e44\u0e2b\u0e21\u0e27\u0e48\u0e32\u0e04\u0e19\u0e23\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e2d\u0e32\u0e0a\u0e35\u0e1e\u0e08\u0e32\u0e01\u0e2d\u0e30\u0e44\u0e23?\u0e04\u0e33\u0e15\u0e2d\u0e1a\u0e2d\u0e32\u0e08\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e41\u0e04\u0e48 &#8220;\u0e04\u0e27\u0e32\u0e21\u0e0a\u0e2d\u0e1a&#8221; \u0e19\u0e30 \ud83d\udc40 \u0e40\u0e1e\u0e23\u0e32\u0e30 \u0e21.\u0e2b\u0e2d\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e44\u0e17\u0e22\u0e2a\u0e33\u0e23\t\t\t<\/a>\n\n\t\t\t\t<\/h4>\n\t\t\n\t\t<div class=\"uael-post__excerpt\">\n\t\t\t\u0e27\u0e31\u0e19\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1b\u0e35\u0e19\u0e35\u0e49 \ud83c\udf89 \u0e25\u0e2d\u0e07\u0e16\u0e32\u0e21\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07\u0e27\u0e48\u0e32 &#8220;\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e48&#8221; \u0e04\u0e37\u0e2d\u0e2d\u0e30\u0e44\u0e23? \u0e23\u0e39\u0e49\u0e44\u0e2b\u0e21\u0e27\u0e48\u0e32\u0e04\u0e19\u0e23\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e2d\u0e32\u0e0a\u0e35\u0e1e\u0e08\u0e32\u0e01\u0e2d\u0e30\u0e44\u0e23?\u0e04\u0e33\u0e15\u0e2d\u0e1a\u0e2d\u0e32\u0e08\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e41\u0e04\u0e48 &#8220;\u0e04\u0e27\u0e32\u0e21\u0e0a\u0e2d\u0e1a&#8221; \u0e19\u0e30 \ud83d\udc40 \u0e40\u0e1e\u0e23\u0e32\u0e30 \u0e21.\u0e2b\u0e2d\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e44\u0e17\u0e22\u0e2a\u0e33\u0e23\u0e27\u0e08\u0e40\u0e14\u0e47\u0e01\u0e23\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48 800+ \u0e04\u0e19 \u0e1e\u0e1a\u0e27\u0e48\u0e32 \u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a 1 \u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e15\u0e31\u0e14\u0e2a\u0e34\u0e19\u0e43\u0e08\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e2d\u0e32\u0e0a\u0e35\u0e1e\u0e04\u0e37\u0e2d ...\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\n\n\t<\/div>\n\n<\/div>\n\n\n<div class=\"uael-post-wrapper   event news \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2b\u0e25\u0e31\u0e01 \">\n\t<div class=\"uael-post__bg-wrap uael-bg-wrap-disabled\">\n\n\t\t\t\t\t<a href=\"https:\/\/imse.kmitl.ac.th\/th\/314853\/\" target=\"_self\" class=\"uael-post__complete-box-overlay\" aria-label=\"Link Complete Box\"><\/a>\n\t\t\t\t\n\t\t<div class=\"uael-post__inner-wrap uael-inner-wrap-disabled\">\n\n\t\t\t\t<div class=\"uael-post__thumbnail \">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"900\" src=\"https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2026\/04\/659320571_1422334613239332_1687318291228948506_n.jpg\" class=\"attachment-full size-full wp-image-314852\" alt=\"\" srcset=\"https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2026\/04\/659320571_1422334613239332_1687318291228948506_n.jpg 720w, https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2026\/04\/659320571_1422334613239332_1687318291228948506_n-240x300.jpg 240w, https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2026\/04\/659320571_1422334613239332_1687318291228948506_n-10x12.jpg 10w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/>\t\t\t\t\t<div class=\"uael-post__datebox \">\n\t\t\t\t<div class=\"uael-post__date-wrap\">\n\t\t\t\t\t\t\t\t\t\t<span class='uael-post__date-month'>\u0e40\u0e21.\u0e22.<\/span><span class='uael-post__date-day'>30<\/span>\t\t\t\t<\/div>\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n\t\t\t\n\t\t\t<div class=\"uael-post__content-wrap uael-content-wrap-disabled\">\n\n\t\t\t\t\t<h4 class=\"uael-post__title\">\n\n\t\t\n\t\t\t\t\t\t<a href=\"https:\/\/imse.kmitl.ac.th\/th\/314853\/\" target=\"_self\">\n\t\t\t\t\u0e42\u0e25\u0e01\u0e43\u0e15\u0e49\u0e19\u0e49\u0e33\u0e44\u0e21\u0e48\u0e40\u0e07\u0e35\u0e22\u0e1a\u0e40\u0e25\u0e22! \ud83c\udf0a\ud83d\udc0b\u2728\n\n\u0e43\u0e04\u0e23\u0e27\u0e48\u0e32\u0e43\u0e15\u0e49\u0e17\u0e30\u0e40\u0e25\u0e08\u0e30\u0e21\u0e35\u0e41\u0e15\u0e48\u0e04\u0e27\u0e32\u0e21\u0e40\u0e07\u0e35\u0e22\u0e1a?\ud83d\udd07 \u0e08\u0e23\u0e34\u0e07\u0e46 \u0e41\u0e25\u0e49\u0e27\u0e42\u0e25\u0e01\u0e43\u0e15\u0e49\u0e19\u0e49\u0e33\u0e40\u0e15\u0e47\u0e21\u0e44\u0e1b\u0e14\u0e49\u0e27\u0e22 &#8220;\u0e40\u0e2a\u0e35\u0e22\u0e07&#8221;\ud83d\udd0a \u0e17\u0e35\u0e48\u0e14\u0e31\u0e07\u0e44\u0e21\u0e48\u0e41\u0e1e\u0e49\u0e1a\u0e19\u0e1a\u0e01 \u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e23\u0e49\u0e2d\u0e07\u0e02\u0e2d\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e30\u0e40\u0e25 \u0e40\u0e2a\t\t\t<\/a>\n\n\t\t\t\t<\/h4>\n\t\t\n\t\t<div class=\"uael-post__excerpt\">\n\t\t\t\u0e42\u0e25\u0e01\u0e43\u0e15\u0e49\u0e19\u0e49\u0e33\u0e44\u0e21\u0e48\u0e40\u0e07\u0e35\u0e22\u0e1a\u0e40\u0e25\u0e22! \ud83c\udf0a\ud83d\udc0b\u2728 \u0e43\u0e04\u0e23\u0e27\u0e48\u0e32\u0e43\u0e15\u0e49\u0e17\u0e30\u0e40\u0e25\u0e08\u0e30\u0e21\u0e35\u0e41\u0e15\u0e48\u0e04\u0e27\u0e32\u0e21\u0e40\u0e07\u0e35\u0e22\u0e1a?\ud83d\udd07 \u0e08\u0e23\u0e34\u0e07\u0e46 \u0e41\u0e25\u0e49\u0e27\u0e42\u0e25\u0e01\u0e43\u0e15\u0e49\u0e19\u0e49\u0e33\u0e40\u0e15\u0e47\u0e21\u0e44\u0e1b\u0e14\u0e49\u0e27\u0e22 &#8220;\u0e40\u0e2a\u0e35\u0e22\u0e07&#8221;\ud83d\udd0a \u0e17\u0e35\u0e48\u0e14\u0e31\u0e07\u0e44\u0e21\u0e48\u0e41\u0e1e\u0e49\u0e1a\u0e19\u0e1a\u0e01 \u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e23\u0e49\u0e2d\u0e07\u0e02\u0e2d\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e30\u0e40\u0e25 \u0e40\u0e2a\u0e35\u0e22\u0e07\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e21\u0e19\u0e38\u0e29\u0e22\u0e4c \u0e44\u0e1b\u0e08\u0e19\u0e16\u0e36\u0e07\u0e1b\u0e23\u0e32\u0e01\u0e0f\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34\ud83c\udf0b \u0e41\u0e21\u0e49\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1a\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e08\u0e30\u0e44\u0e21\u0e48\u0e21\u0e35 &#8220;\u0e2b\u0e39&#8221; \u0e41\u0e1a\u0e1a\u0e40\u0e23\u0e32 \u0e41\u0e15\u0e48\u0e1e\u0e27\u0e01\u0e21\u0e31\u0e19\u0e23\u0e31\u0e1a\u0e23\u0e39\u0e49\u0e41\u0e23\u0e07\u0e2a\u0e31\u0e48\u0e19\u0e2a\u0e30\u0e40\u0e17\u0e37\u0e2d\u0e19\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e35\u0e49\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e0a\u0e49\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e41\u0e25\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e01\u0e31\u0e19\u0e15\u0e25\u0e2d\u0e14\u0e40\u0e27\u0e25\u0e32\ud83d\udcac \u0e25\u0e2d\u0e07\u0e21\u0e32\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e01\u0e31\u0e19\u0e14\u0e39\u0e27\u0e48\u0e32 \u0e40\u0e2a\u0e35\u0e22\u0e07\u0e43\u0e15\u0e49\u0e19\u0e49\u0e33\u0e41\u0e15\u0e48\u0e25\u0e30\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e14\u0e31\u0e07\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e40\u0e17\u0e48\u0e32\u0e01\u0e31\u0e1a\u0e2d\u0e30\u0e44\u0e23\u0e1a\u0e19\u0e1a\u0e01\u0e1a\u0e49\u0e32\u0e07? (\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e14\u0e31\u0e07\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 ...\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\n\n\t<\/div>\n\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t<div class=\"uael-post__footer\">\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7231eeb uael-button-halign-center uael-button-stack-none elementor-widget elementor-widget-uael-buttons\" data-id=\"7231eeb\" data-element_type=\"widget\" data-widget_type=\"uael-buttons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"uael-dual-button-outer-wrap\">\n\t\t\t<div class=\"uael-dual-button-wrap\">\n\t\t\t\t\t\t\t\t<div class=\"uael-button-wrapper uael-dual-button elementor-widget-button elementor-repeater-item-b7e8120 uael-dual-button-0\">\n\t\t\t\t\t<a class=\"elementor-button-link elementor-button elementor-size-lg elementor-button-link\" href=\"https:\/\/imse.kmitl.ac.th\/event\">\n\t\t\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper uael-buttons-icon-\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-align-icon- elementor-button-icon\">\n\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text elementor-inline-editing\" data-elementor-setting-key=\"buttons.0.text\" data-elementor-inline-editing-toolbar=\"none\">\u0e14\u0e39\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14<\/span>\n\t\t<\/span>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5da64c1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5da64c1\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_scale_effect&quot;:&quot;yes&quot;,&quot;motion_fx_scale_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;733172a&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:null,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}],&quot;motion_fx_scale_direction&quot;:&quot;out-in&quot;,&quot;motion_fx_scale_range&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:20,&quot;end&quot;:80}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7c8a1d6\" data-id=\"7c8a1d6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4efb0ad uael-heading-align-center elementor-widget elementor-widget-uael-advanced-heading\" data-id=\"4efb0ad\" data-element_type=\"widget\" data-widget_type=\"uael-advanced-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"uael-module-content uael-heading-wrapper\">\n\t\t\t\t\t\t\n\t\t\t<h6 class=\"uael-heading\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-heading-text elementor-inline-editing uael-size--default\" data-elementor-setting-key=\"heading_title\" data-elementor-inline-editing-toolbar=\"basic\">IMSE  NEWS<\/span>\n\t\t\t\t\t\t\t<\/h6>\n\n\t\t\t\t\t\t\t<div class=\"uael-sub-heading elementor-inline-editing\" data-elementor-setting-key=\"sub_heading\" data-elementor-inline-editing-toolbar=\"advanced\" >\u0e02\u0e48\u0e32\u0e27\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-50c96d6 elementor-grid-3 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-posts--thumbnail-top elementor-posts--show-avatar elementor-card-shadow-yes elementor-posts__hover-gradient elementor-widget elementor-widget-posts\" data-id=\"50c96d6\" data-element_type=\"widget\" data-settings=\"{&quot;cards_columns&quot;:&quot;3&quot;,&quot;cards_columns_tablet&quot;:&quot;2&quot;,&quot;cards_columns_mobile&quot;:&quot;1&quot;,&quot;cards_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:35,&quot;sizes&quot;:[]},&quot;cards_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;cards_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.cards\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-cards elementor-grid\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-314884 post type-post status-publish format-standard has-post-thumbnail hentry category-event category-news category-main-activities\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/imse.kmitl.ac.th\/th\/314884\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2026\/05\/696588678_1458360029636790_4463462866560711166_n-300x300.jpg\" class=\"attachment-medium size-medium wp-image-314883\" alt=\"\" srcset=\"https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2026\/05\/696588678_1458360029636790_4463462866560711166_n-300x300.jpg 300w, https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2026\/05\/696588678_1458360029636790_4463462866560711166_n-150x150.jpg 150w, https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2026\/05\/696588678_1458360029636790_4463462866560711166_n-12x12.jpg 12w, https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2026\/05\/696588678_1458360029636790_4463462866560711166_n.jpg 720w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Event<\/div>\n\t\t\t\t<div class=\"elementor-post__avatar\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/imse.kmitl.ac.th\/th\/314884\/\" >\n\t\t\t\t\u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e43\u0e19 IMSE\n4 \u0e1b\u0e35 \u0e40\u0e23\u0e35\u0e22\u0e19\u0e2d\u0e30\u0e44\u0e23\u0e1a\u0e49\u0e32\u0e07? \ud83d\udc40\n\n\u0e2b\u0e25\u0e32\u0e22\u0e04\u0e19\u0e2a\u0e07\u0e2a\u0e31\u0e22\u0e27\u0e48\u0e32\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e41\u0e25\u0e49\u0e27\u0e08\u0e30\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2d\u0e30\u0e44\u0e23 \u0e1a\u0e2d\u0e01\u0e40\u0e25\u0e22\u0e27\u0e48\u0e32\u0e17\u0e35\u0e48\u0e19\u0e35\u0e48\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e21\u0e35\u0e41\u0e04\u0e48\u0e17\u0e32\u0e07\u0e40\u0e14\u0e35\u0e22\u0e27 \ud83c\udfaf\n\n\u0e17\u0e35\u0e48 IMSE \u0e21\u0e35 3 \u0e41\u0e02\u0e19\u0e07\u0e43\u0e2b\u0e49\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e15\u0e32\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>\u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e43\u0e19 IMSE 4 \u0e1b\u0e35 \u0e40\u0e23\u0e35\u0e22\u0e19\u0e2d\u0e30\u0e44\u0e23\u0e1a\u0e49\u0e32\u0e07? \ud83d\udc40 \u0e2b\u0e25\u0e32\u0e22\u0e04\u0e19\u0e2a\u0e07\u0e2a\u0e31\u0e22\u0e27\u0e48\u0e32\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e41\u0e25\u0e49\u0e27\u0e08\u0e30\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2d\u0e30\u0e44\u0e23 \u0e1a\u0e2d\u0e01\u0e40\u0e25\u0e22\u0e27\u0e48\u0e32\u0e17\u0e35\u0e48\u0e19\u0e35\u0e48\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e21\u0e35\u0e41\u0e04\u0e48\u0e17\u0e32\u0e07\u0e40\u0e14\u0e35\u0e22\u0e27 \ud83c\udfaf \u0e17\u0e35\u0e48 IMSE \u0e21\u0e35 3 \u0e41\u0e02\u0e19\u0e07\u0e43\u0e2b\u0e49\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e15\u0e32\u0e21\u0e2a\u0e32\u0e22\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e48\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e04\u0e38\u0e13 \ud83c\udf93 \ud83c\udfa7 Audio Engineering \u2014 \u0e2a\u0e32\u0e22\u0e40\u0e2a\u0e35\u0e22\u0e07 \u0e2a\u0e32\u0e22\u0e14\u0e19\u0e15\u0e23\u0e35 \u0e2a\u0e32\u0e22\u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48 acoustic, recording \u0e22\u0e31\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e21\u0e37\u0e2d\u0e2d\u0e32\u0e0a\u0e35\u0e1e \ud83d\udd0a Acoustical Engineering \u2014<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/imse.kmitl.ac.th\/th\/314884\/\" aria-label=\"Read more about \u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e43\u0e19 IMSE\n4 \u0e1b\u0e35 \u0e40\u0e23\u0e35\u0e22\u0e19\u0e2d\u0e30\u0e44\u0e23\u0e1a\u0e49\u0e32\u0e07? \ud83d\udc40\n\n\u0e2b\u0e25\u0e32\u0e22\u0e04\u0e19\u0e2a\u0e07\u0e2a\u0e31\u0e22\u0e27\u0e48\u0e32\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e41\u0e25\u0e49\u0e27\u0e08\u0e30\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2d\u0e30\u0e44\u0e23 \u0e1a\u0e2d\u0e01\u0e40\u0e25\u0e22\u0e27\u0e48\u0e32\u0e17\u0e35\u0e48\u0e19\u0e35\u0e48\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e21\u0e35\u0e41\u0e04\u0e48\u0e17\u0e32\u0e07\u0e40\u0e14\u0e35\u0e22\u0e27 \ud83c\udfaf\n\n\u0e17\u0e35\u0e48 IMSE \u0e21\u0e35 3 \u0e41\u0e02\u0e19\u0e07\u0e43\u0e2b\u0e49\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e15\u0e32\" tabindex=\"-1\" >\n\t\t\tRead More \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-314870 post type-post status-publish format-standard has-post-thumbnail hentry category-event category-news category-main-activities\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/imse.kmitl.ac.th\/th\/314870\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2026\/05\/695536701_1453533683452758_5012916895820910949_n-300x169.jpg\" class=\"attachment-medium size-medium wp-image-314869\" alt=\"\" srcset=\"https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2026\/05\/695536701_1453533683452758_5012916895820910949_n-300x169.jpg 300w, https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2026\/05\/695536701_1453533683452758_5012916895820910949_n-1024x576.jpg 1024w, https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2026\/05\/695536701_1453533683452758_5012916895820910949_n-768x432.jpg 768w, https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2026\/05\/695536701_1453533683452758_5012916895820910949_n-18x10.jpg 18w, https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2026\/05\/695536701_1453533683452758_5012916895820910949_n.jpg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Event<\/div>\n\t\t\t\t<div class=\"elementor-post__avatar\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/imse.kmitl.ac.th\/th\/314870\/\" >\n\t\t\t\t\u0e02\u0e2d\u0e2d\u0e20\u0e31\u0e22\u0e43\u0e19\u0e04\u0e27\u0e32\u0e21\u0e44\u0e21\u0e48\u0e2a\u0e30\u0e14\u0e27\u0e01\ud83d\ude4f\n#IMSE  #KMITL\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>\u0e02\u0e2d\u0e2d\u0e20\u0e31\u0e22\u0e43\u0e19\u0e04\u0e27\u0e32\u0e21\u0e44\u0e21\u0e48\u0e2a\u0e30\u0e14\u0e27\u0e01\ud83d\ude4f #IMSE #KMITL<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/imse.kmitl.ac.th\/th\/314870\/\" aria-label=\"Read more about \u0e02\u0e2d\u0e2d\u0e20\u0e31\u0e22\u0e43\u0e19\u0e04\u0e27\u0e32\u0e21\u0e44\u0e21\u0e48\u0e2a\u0e30\u0e14\u0e27\u0e01\ud83d\ude4f\n#IMSE  #KMITL\" tabindex=\"-1\" >\n\t\t\tRead More \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-314859 post type-post status-publish format-standard has-post-thumbnail hentry category-event category-news category-main-activities\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/imse.kmitl.ac.th\/th\/314859\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2026\/05\/690128755_1451550386984421_578924563119446962_n-300x300.jpg\" class=\"attachment-medium size-medium wp-image-314858\" alt=\"\" srcset=\"https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2026\/05\/690128755_1451550386984421_578924563119446962_n-300x300.jpg 300w, https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2026\/05\/690128755_1451550386984421_578924563119446962_n-150x150.jpg 150w, https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2026\/05\/690128755_1451550386984421_578924563119446962_n-12x12.jpg 12w, https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2026\/05\/690128755_1451550386984421_578924563119446962_n.jpg 720w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Event<\/div>\n\t\t\t\t<div class=\"elementor-post__avatar\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/imse.kmitl.ac.th\/th\/314859\/\" >\n\t\t\t\t\u0e17\u0e23\u0e07\u0e1e\u0e23\u0e30\u0e40\u0e08\u0e23\u0e34\u0e0d\n\u0e55 \u0e1e\u0e24\u0e29\u0e20\u0e32\u0e04\u0e21\n\u0e27\u0e31\u0e19\u0e04\u0e25\u0e49\u0e32\u0e22\u0e27\u0e31\u0e19\u0e1b\u0e23\u0e30\u0e2a\u0e39\u0e15\u0e34\n\u0e1e\u0e23\u0e30\u0e40\u0e08\u0e49\u0e32\u0e27\u0e23\u0e27\u0e07\u0e28\u0e4c\u0e40\u0e18\u0e2d \u0e1e\u0e23\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e40\u0e08\u0e49\u0e32\u0e2d\u0e17\u0e34\u0e15\u0e22\u0e32\u0e17\u0e23\u0e01\u0e34\u0e15\u0e34\u0e04\u0e38\u0e13\n\u0e04\u0e27\u0e23\u0e21\u0e34\u0e04\u0e27\u0e23\u0e41\u0e25\u0e49\u0e27\u0e41\u0e15\u0e48\u0e08\u0e30\u0e42\u0e1b\u0e23\u0e14\n\u0e40\u0e01\u0e25\u0e49\u0e32\u0e01\u0e23\u0e30\u0e2b\u0e21\u0e48\u0e2d\u0e21 \u0e04\u0e13\u0e30\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e04\u0e13\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>\u0e17\u0e23\u0e07\u0e1e\u0e23\u0e30\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e55 \u0e1e\u0e24\u0e29\u0e20\u0e32\u0e04\u0e21 \u0e27\u0e31\u0e19\u0e04\u0e25\u0e49\u0e32\u0e22\u0e27\u0e31\u0e19\u0e1b\u0e23\u0e30\u0e2a\u0e39\u0e15\u0e34 \u0e1e\u0e23\u0e30\u0e40\u0e08\u0e49\u0e32\u0e27\u0e23\u0e27\u0e07\u0e28\u0e4c\u0e40\u0e18\u0e2d \u0e1e\u0e23\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e40\u0e08\u0e49\u0e32\u0e2d\u0e17\u0e34\u0e15\u0e22\u0e32\u0e17\u0e23\u0e01\u0e34\u0e15\u0e34\u0e04\u0e38\u0e13 \u0e04\u0e27\u0e23\u0e21\u0e34\u0e04\u0e27\u0e23\u0e41\u0e25\u0e49\u0e27\u0e41\u0e15\u0e48\u0e08\u0e30\u0e42\u0e1b\u0e23\u0e14 \u0e40\u0e01\u0e25\u0e49\u0e32\u0e01\u0e23\u0e30\u0e2b\u0e21\u0e48\u0e2d\u0e21 \u0e04\u0e13\u0e30\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e04\u0e13\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23 \u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e28\u0e34\u0e29\u0e22\u0e4c\u0e40\u0e01\u0e48\u0e32 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e31\u0e07\u0e04\u0e35\u0e15 \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e1e\u0e23\u0e30\u0e08\u0e2d\u0e21\u0e40\u0e01\u0e25\u0e49\u0e32\u0e40\u0e08\u0e49\u0e32\u0e04\u0e38\u0e13\u0e17\u0e2b\u0e32\u0e23\u0e25\u0e32\u0e14\u0e01\u0e23\u0e30\u0e1a\u0e31\u0e07<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/imse.kmitl.ac.th\/th\/314859\/\" aria-label=\"Read more about \u0e17\u0e23\u0e07\u0e1e\u0e23\u0e30\u0e40\u0e08\u0e23\u0e34\u0e0d\n\u0e55 \u0e1e\u0e24\u0e29\u0e20\u0e32\u0e04\u0e21\n\u0e27\u0e31\u0e19\u0e04\u0e25\u0e49\u0e32\u0e22\u0e27\u0e31\u0e19\u0e1b\u0e23\u0e30\u0e2a\u0e39\u0e15\u0e34\n\u0e1e\u0e23\u0e30\u0e40\u0e08\u0e49\u0e32\u0e27\u0e23\u0e27\u0e07\u0e28\u0e4c\u0e40\u0e18\u0e2d \u0e1e\u0e23\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e40\u0e08\u0e49\u0e32\u0e2d\u0e17\u0e34\u0e15\u0e22\u0e32\u0e17\u0e23\u0e01\u0e34\u0e15\u0e34\u0e04\u0e38\u0e13\n\u0e04\u0e27\u0e23\u0e21\u0e34\u0e04\u0e27\u0e23\u0e41\u0e25\u0e49\u0e27\u0e41\u0e15\u0e48\u0e08\u0e30\u0e42\u0e1b\u0e23\u0e14\n\u0e40\u0e01\u0e25\u0e49\u0e32\u0e01\u0e23\u0e30\u0e2b\u0e21\u0e48\u0e2d\u0e21 \u0e04\u0e13\u0e30\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e04\u0e13\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\" tabindex=\"-1\" >\n\t\t\tRead More \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-314857 post type-post status-publish format-standard has-post-thumbnail hentry category-event category-news category-main-activities\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/imse.kmitl.ac.th\/th\/314857\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"169\" height=\"300\" src=\"https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2026\/05\/687924091_27800084659580029_4160118339138478514_n-169x300.jpg\" class=\"attachment-medium size-medium wp-image-314856\" alt=\"\" srcset=\"https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2026\/05\/687924091_27800084659580029_4160118339138478514_n-169x300.jpg 169w, https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2026\/05\/687924091_27800084659580029_4160118339138478514_n-576x1024.jpg 576w, https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2026\/05\/687924091_27800084659580029_4160118339138478514_n-768x1365.jpg 768w, https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2026\/05\/687924091_27800084659580029_4160118339138478514_n-864x1536.jpg 864w, https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2026\/05\/687924091_27800084659580029_4160118339138478514_n-7x12.jpg 7w, https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2026\/05\/687924091_27800084659580029_4160118339138478514_n.jpg 1080w\" sizes=\"(max-width: 169px) 100vw, 169px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Event<\/div>\n\t\t\t\t<div class=\"elementor-post__avatar\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/imse.kmitl.ac.th\/th\/314857\/\" >\n\t\t\t\tTCAS \u0e23\u0e2d\u0e1a Admission \n\u0e08\u0e31\u0e14\u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a\u0e22\u0e31\u0e07\u0e44\u0e07\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e15\u0e34\u0e14\u0e21\u0e32\u0e01\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14? \ud83c\udfaf\n\n\u0e19\u0e49\u0e2d\u0e07\u0e46 \u0e23\u0e39\u0e49\u0e08\u0e31\u0e01\u0e23\u0e30\u0e1a\u0e1a\u0e19\u0e35\u0e49\u0e14\u0e35\u0e1e\u0e2d\u0e41\u0e25\u0e49\u0e27\u0e22\u0e31\u0e07? \ud83d\udc40 \u0e21\u0e32\u0e40\u0e0a\u0e47\u0e01\u0e43\u0e2b\u0e49\u0e0a\u0e31\u0e27\u0e23\u0e4c\u0e01\u0e48\u0e2d\u0e19\u0e01\u0e14\u0e2a\u0e48\u0e07\u0e01\u0e31\u0e19 \u0e40\u0e25\u0e37\u0e2d\u0e01\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14 10 \u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a \u0e41\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>TCAS \u0e23\u0e2d\u0e1a Admission \u0e08\u0e31\u0e14\u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a\u0e22\u0e31\u0e07\u0e44\u0e07\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e15\u0e34\u0e14\u0e21\u0e32\u0e01\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14? \ud83c\udfaf \u0e19\u0e49\u0e2d\u0e07\u0e46 \u0e23\u0e39\u0e49\u0e08\u0e31\u0e01\u0e23\u0e30\u0e1a\u0e1a\u0e19\u0e35\u0e49\u0e14\u0e35\u0e1e\u0e2d\u0e41\u0e25\u0e49\u0e27\u0e22\u0e31\u0e07? \ud83d\udc40 \u0e21\u0e32\u0e40\u0e0a\u0e47\u0e01\u0e43\u0e2b\u0e49\u0e0a\u0e31\u0e27\u0e23\u0e4c\u0e01\u0e48\u0e2d\u0e19\u0e01\u0e14\u0e2a\u0e48\u0e07\u0e01\u0e31\u0e19 \u0e40\u0e25\u0e37\u0e2d\u0e01\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14 10 \u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a \u0e41\u0e15\u0e48\u0e15\u0e34\u0e14\u0e44\u0e14\u0e49\u0e41\u0e04\u0e48\u0e17\u0e35\u0e48\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e08\u0e30\u0e44\u0e25\u0e48\u0e08\u0e32\u0e01\u0e1a\u0e19\u0e25\u0e07\u0e25\u0e48\u0e32\u0e07\u0e40\u0e25\u0e22\u0e19\u0e30 \ud83d\udccb \u0e02\u0e2d\u0e41\u0e19\u0e30\u0e19\u0e33\u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e15\u0e32\u0e21\u0e19\u0e35\u0e49\u0e40\u0e25\u0e22 \ud83d\udc47 \ud83c\udfc6 \u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a 1\u20133 : \u0e04\u0e13\u0e30\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e32\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19\u0e08\u0e23\u0e34\u0e07\u0e46 \ud83c\udfaf \u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a 4\u20136 : \u0e04\u0e13\u0e30\u0e17\u0e35\u0e48\u0e2a\u0e19\u0e43\u0e08\u0e23\u0e2d\u0e07 \u0e04\u0e30\u0e41\u0e19\u0e19\u0e43\u0e01\u0e25\u0e49\u0e40\u0e04\u0e35\u0e22\u0e07\u0e1b\u0e35\u0e17\u0e35\u0e48\u0e41\u0e25\u0e49\u0e27 \ud83d\udee1\ufe0f \u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/imse.kmitl.ac.th\/th\/314857\/\" aria-label=\"Read more about TCAS \u0e23\u0e2d\u0e1a Admission \n\u0e08\u0e31\u0e14\u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a\u0e22\u0e31\u0e07\u0e44\u0e07\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e15\u0e34\u0e14\u0e21\u0e32\u0e01\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14? \ud83c\udfaf\n\n\u0e19\u0e49\u0e2d\u0e07\u0e46 \u0e23\u0e39\u0e49\u0e08\u0e31\u0e01\u0e23\u0e30\u0e1a\u0e1a\u0e19\u0e35\u0e49\u0e14\u0e35\u0e1e\u0e2d\u0e41\u0e25\u0e49\u0e27\u0e22\u0e31\u0e07? \ud83d\udc40 \u0e21\u0e32\u0e40\u0e0a\u0e47\u0e01\u0e43\u0e2b\u0e49\u0e0a\u0e31\u0e27\u0e23\u0e4c\u0e01\u0e48\u0e2d\u0e19\u0e01\u0e14\u0e2a\u0e48\u0e07\u0e01\u0e31\u0e19 \u0e40\u0e25\u0e37\u0e2d\u0e01\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14 10 \u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a \u0e41\" tabindex=\"-1\" >\n\t\t\tRead More \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-314855 post type-post status-publish format-standard has-post-thumbnail hentry category-event category-news category-main-activities\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/imse.kmitl.ac.th\/th\/314855\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"169\" height=\"300\" src=\"https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2026\/05\/682664637_4338955669693224_2827702057543468072_n-169x300.jpg\" class=\"attachment-medium size-medium wp-image-314854\" alt=\"\" srcset=\"https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2026\/05\/682664637_4338955669693224_2827702057543468072_n-169x300.jpg 169w, https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2026\/05\/682664637_4338955669693224_2827702057543468072_n-576x1024.jpg 576w, https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2026\/05\/682664637_4338955669693224_2827702057543468072_n-768x1365.jpg 768w, https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2026\/05\/682664637_4338955669693224_2827702057543468072_n-864x1536.jpg 864w, https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2026\/05\/682664637_4338955669693224_2827702057543468072_n-7x12.jpg 7w, https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2026\/05\/682664637_4338955669693224_2827702057543468072_n.jpg 1080w\" sizes=\"(max-width: 169px) 100vw, 169px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Event<\/div>\n\t\t\t\t<div class=\"elementor-post__avatar\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/imse.kmitl.ac.th\/th\/314855\/\" >\n\t\t\t\t\u0e27\u0e31\u0e19\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1b\u0e35\u0e19\u0e35\u0e49 \ud83c\udf89\n\u0e25\u0e2d\u0e07\u0e16\u0e32\u0e21\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07\u0e27\u0e48\u0e32 &#8220;\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e48&#8221;  \u0e04\u0e37\u0e2d\u0e2d\u0e30\u0e44\u0e23?\n\n\u0e23\u0e39\u0e49\u0e44\u0e2b\u0e21\u0e27\u0e48\u0e32\u0e04\u0e19\u0e23\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e2d\u0e32\u0e0a\u0e35\u0e1e\u0e08\u0e32\u0e01\u0e2d\u0e30\u0e44\u0e23?\u0e04\u0e33\u0e15\u0e2d\u0e1a\u0e2d\u0e32\u0e08\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e41\u0e04\u0e48 &#8220;\u0e04\u0e27\u0e32\u0e21\u0e0a\u0e2d\u0e1a&#8221; \u0e19\u0e30 \ud83d\udc40 \u0e40\u0e1e\u0e23\u0e32\u0e30 \u0e21.\u0e2b\u0e2d\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e44\u0e17\u0e22\u0e2a\u0e33\u0e23\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>\u0e27\u0e31\u0e19\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1b\u0e35\u0e19\u0e35\u0e49 \ud83c\udf89 \u0e25\u0e2d\u0e07\u0e16\u0e32\u0e21\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07\u0e27\u0e48\u0e32 &#8220;\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e48&#8221; \u0e04\u0e37\u0e2d\u0e2d\u0e30\u0e44\u0e23? \u0e23\u0e39\u0e49\u0e44\u0e2b\u0e21\u0e27\u0e48\u0e32\u0e04\u0e19\u0e23\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e2d\u0e32\u0e0a\u0e35\u0e1e\u0e08\u0e32\u0e01\u0e2d\u0e30\u0e44\u0e23?\u0e04\u0e33\u0e15\u0e2d\u0e1a\u0e2d\u0e32\u0e08\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e41\u0e04\u0e48 &#8220;\u0e04\u0e27\u0e32\u0e21\u0e0a\u0e2d\u0e1a&#8221; \u0e19\u0e30 \ud83d\udc40 \u0e40\u0e1e\u0e23\u0e32\u0e30 \u0e21.\u0e2b\u0e2d\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e44\u0e17\u0e22\u0e2a\u0e33\u0e23\u0e27\u0e08\u0e40\u0e14\u0e47\u0e01\u0e23\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48 800+ \u0e04\u0e19 \u0e1e\u0e1a\u0e27\u0e48\u0e32 \u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a 1 \u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e15\u0e31\u0e14\u0e2a\u0e34\u0e19\u0e43\u0e08\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e2d\u0e32\u0e0a\u0e35\u0e1e\u0e04\u0e37\u0e2d \ud83d\udc49 &#8220;\u0e21\u0e35\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e07\u0e32\u0e19\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a&#8221; \u0e41\u0e25\u0e49\u0e27\u0e2a\u0e32\u0e22\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e41\u0e25\u0e30\u0e21\u0e35\u0e40\u0e14\u0e35\u0e22\u0e15\u0e2d\u0e1a\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e02\u0e49\u0e2d\u0e19\u0e35\u0e49\u0e44\u0e14\u0e49\u0e44\u0e2b\u0e21? \u0e40\u0e23\u0e32\u0e44\u0e1b\u0e14\u0e39\u0e15\u0e31\u0e27\u0e40\u0e25\u0e02\u0e08\u0e23\u0e34\u0e07\u0e01\u0e31\u0e19 \ud83d\udcca \ud83d\udccc Jobsdb \u0e40\u0e14\u0e37\u0e2d\u0e19 \u0e40\u0e21.\u0e22. 2026 \u0e40\u0e09\u0e1e\u0e32\u0e30\u0e43\u0e19\u0e44\u0e17\u0e22 \u2014 UX\/UI<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/imse.kmitl.ac.th\/th\/314855\/\" aria-label=\"Read more about \u0e27\u0e31\u0e19\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1b\u0e35\u0e19\u0e35\u0e49 \ud83c\udf89\n\u0e25\u0e2d\u0e07\u0e16\u0e32\u0e21\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07\u0e27\u0e48\u0e32 &#8220;\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e48&#8221;  \u0e04\u0e37\u0e2d\u0e2d\u0e30\u0e44\u0e23?\n\n\u0e23\u0e39\u0e49\u0e44\u0e2b\u0e21\u0e27\u0e48\u0e32\u0e04\u0e19\u0e23\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e2d\u0e32\u0e0a\u0e35\u0e1e\u0e08\u0e32\u0e01\u0e2d\u0e30\u0e44\u0e23?\u0e04\u0e33\u0e15\u0e2d\u0e1a\u0e2d\u0e32\u0e08\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e41\u0e04\u0e48 &#8220;\u0e04\u0e27\u0e32\u0e21\u0e0a\u0e2d\u0e1a&#8221; \u0e19\u0e30 \ud83d\udc40 \u0e40\u0e1e\u0e23\u0e32\u0e30 \u0e21.\u0e2b\u0e2d\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e44\u0e17\u0e22\u0e2a\u0e33\u0e23\" tabindex=\"-1\" >\n\t\t\tRead More \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-314853 post type-post status-publish format-standard has-post-thumbnail hentry category-event category-news category-main-activities\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/imse.kmitl.ac.th\/th\/314853\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"240\" height=\"300\" src=\"https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2026\/04\/659320571_1422334613239332_1687318291228948506_n-240x300.jpg\" class=\"attachment-medium size-medium wp-image-314852\" alt=\"\" srcset=\"https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2026\/04\/659320571_1422334613239332_1687318291228948506_n-240x300.jpg 240w, https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2026\/04\/659320571_1422334613239332_1687318291228948506_n-10x12.jpg 10w, https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2026\/04\/659320571_1422334613239332_1687318291228948506_n.jpg 720w\" sizes=\"(max-width: 240px) 100vw, 240px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Event<\/div>\n\t\t\t\t<div class=\"elementor-post__avatar\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/imse.kmitl.ac.th\/th\/314853\/\" >\n\t\t\t\t\u0e42\u0e25\u0e01\u0e43\u0e15\u0e49\u0e19\u0e49\u0e33\u0e44\u0e21\u0e48\u0e40\u0e07\u0e35\u0e22\u0e1a\u0e40\u0e25\u0e22! \ud83c\udf0a\ud83d\udc0b\u2728\n\n\u0e43\u0e04\u0e23\u0e27\u0e48\u0e32\u0e43\u0e15\u0e49\u0e17\u0e30\u0e40\u0e25\u0e08\u0e30\u0e21\u0e35\u0e41\u0e15\u0e48\u0e04\u0e27\u0e32\u0e21\u0e40\u0e07\u0e35\u0e22\u0e1a?\ud83d\udd07 \u0e08\u0e23\u0e34\u0e07\u0e46 \u0e41\u0e25\u0e49\u0e27\u0e42\u0e25\u0e01\u0e43\u0e15\u0e49\u0e19\u0e49\u0e33\u0e40\u0e15\u0e47\u0e21\u0e44\u0e1b\u0e14\u0e49\u0e27\u0e22 &#8220;\u0e40\u0e2a\u0e35\u0e22\u0e07&#8221;\ud83d\udd0a \u0e17\u0e35\u0e48\u0e14\u0e31\u0e07\u0e44\u0e21\u0e48\u0e41\u0e1e\u0e49\u0e1a\u0e19\u0e1a\u0e01 \u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e23\u0e49\u0e2d\u0e07\u0e02\u0e2d\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e30\u0e40\u0e25 \u0e40\u0e2a\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>\u0e42\u0e25\u0e01\u0e43\u0e15\u0e49\u0e19\u0e49\u0e33\u0e44\u0e21\u0e48\u0e40\u0e07\u0e35\u0e22\u0e1a\u0e40\u0e25\u0e22! \ud83c\udf0a\ud83d\udc0b\u2728 \u0e43\u0e04\u0e23\u0e27\u0e48\u0e32\u0e43\u0e15\u0e49\u0e17\u0e30\u0e40\u0e25\u0e08\u0e30\u0e21\u0e35\u0e41\u0e15\u0e48\u0e04\u0e27\u0e32\u0e21\u0e40\u0e07\u0e35\u0e22\u0e1a?\ud83d\udd07 \u0e08\u0e23\u0e34\u0e07\u0e46 \u0e41\u0e25\u0e49\u0e27\u0e42\u0e25\u0e01\u0e43\u0e15\u0e49\u0e19\u0e49\u0e33\u0e40\u0e15\u0e47\u0e21\u0e44\u0e1b\u0e14\u0e49\u0e27\u0e22 &#8220;\u0e40\u0e2a\u0e35\u0e22\u0e07&#8221;\ud83d\udd0a \u0e17\u0e35\u0e48\u0e14\u0e31\u0e07\u0e44\u0e21\u0e48\u0e41\u0e1e\u0e49\u0e1a\u0e19\u0e1a\u0e01 \u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e23\u0e49\u0e2d\u0e07\u0e02\u0e2d\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e30\u0e40\u0e25 \u0e40\u0e2a\u0e35\u0e22\u0e07\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e21\u0e19\u0e38\u0e29\u0e22\u0e4c \u0e44\u0e1b\u0e08\u0e19\u0e16\u0e36\u0e07\u0e1b\u0e23\u0e32\u0e01\u0e0f\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34\ud83c\udf0b \u0e41\u0e21\u0e49\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1a\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e08\u0e30\u0e44\u0e21\u0e48\u0e21\u0e35 &#8220;\u0e2b\u0e39&#8221; \u0e41\u0e1a\u0e1a\u0e40\u0e23\u0e32 \u0e41\u0e15\u0e48\u0e1e\u0e27\u0e01\u0e21\u0e31\u0e19\u0e23\u0e31\u0e1a\u0e23\u0e39\u0e49\u0e41\u0e23\u0e07\u0e2a\u0e31\u0e48\u0e19\u0e2a\u0e30\u0e40\u0e17\u0e37\u0e2d\u0e19\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e35\u0e49\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e0a\u0e49\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e41\u0e25\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e01\u0e31\u0e19\u0e15\u0e25\u0e2d\u0e14\u0e40\u0e27\u0e25\u0e32\ud83d\udcac \u0e25\u0e2d\u0e07\u0e21\u0e32\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e01\u0e31\u0e19\u0e14\u0e39\u0e27\u0e48\u0e32 \u0e40\u0e2a\u0e35\u0e22\u0e07\u0e43\u0e15\u0e49\u0e19\u0e49\u0e33\u0e41\u0e15\u0e48\u0e25\u0e30\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e14\u0e31\u0e07\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e40\u0e17\u0e48\u0e32\u0e01\u0e31\u0e1a\u0e2d\u0e30\u0e44\u0e23\u0e1a\u0e19\u0e1a\u0e01\u0e1a\u0e49\u0e32\u0e07? (\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e14\u0e31\u0e07\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 dB SPL) \ud83e\udee7 \u0e04\u0e25\u0e37\u0e48\u0e19 \/ \u0e1f\u0e2d\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28 (40\u201380 dB): \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1e\u0e2d\u0e46 \u0e01\u0e31\u0e1a\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e1a\u0e17\u0e2a\u0e19\u0e17\u0e19\u0e32\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \ud83d\udc0b \u0e27\u0e32\u0e2c (90\u2013120<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/imse.kmitl.ac.th\/th\/314853\/\" aria-label=\"Read more about \u0e42\u0e25\u0e01\u0e43\u0e15\u0e49\u0e19\u0e49\u0e33\u0e44\u0e21\u0e48\u0e40\u0e07\u0e35\u0e22\u0e1a\u0e40\u0e25\u0e22! \ud83c\udf0a\ud83d\udc0b\u2728\n\n\u0e43\u0e04\u0e23\u0e27\u0e48\u0e32\u0e43\u0e15\u0e49\u0e17\u0e30\u0e40\u0e25\u0e08\u0e30\u0e21\u0e35\u0e41\u0e15\u0e48\u0e04\u0e27\u0e32\u0e21\u0e40\u0e07\u0e35\u0e22\u0e1a?\ud83d\udd07 \u0e08\u0e23\u0e34\u0e07\u0e46 \u0e41\u0e25\u0e49\u0e27\u0e42\u0e25\u0e01\u0e43\u0e15\u0e49\u0e19\u0e49\u0e33\u0e40\u0e15\u0e47\u0e21\u0e44\u0e1b\u0e14\u0e49\u0e27\u0e22 &#8220;\u0e40\u0e2a\u0e35\u0e22\u0e07&#8221;\ud83d\udd0a \u0e17\u0e35\u0e48\u0e14\u0e31\u0e07\u0e44\u0e21\u0e48\u0e41\u0e1e\u0e49\u0e1a\u0e19\u0e1a\u0e01 \u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e23\u0e49\u0e2d\u0e07\u0e02\u0e2d\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e30\u0e40\u0e25 \u0e40\u0e2a\" tabindex=\"-1\" >\n\t\t\tRead More \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9ad9d15 uael-button-halign-center uael-button-stack-none elementor-widget elementor-widget-uael-buttons\" data-id=\"9ad9d15\" data-element_type=\"widget\" data-widget_type=\"uael-buttons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"uael-dual-button-outer-wrap\">\n\t\t\t<div class=\"uael-dual-button-wrap\">\n\t\t\t\t\t\t\t\t<div class=\"uael-button-wrapper uael-dual-button elementor-widget-button elementor-repeater-item-b7e8120 uael-dual-button-0\">\n\t\t\t\t\t<a class=\"elementor-button-link elementor-button elementor-size-lg elementor-button-link\" href=\"https:\/\/imse.kmitl.ac.th\/news\/\">\n\t\t\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper uael-buttons-icon-\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-align-icon- elementor-button-icon\">\n\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text elementor-inline-editing\" data-elementor-setting-key=\"buttons.0.text\" data-elementor-inline-editing-toolbar=\"none\">\u0e14\u0e39\u0e02\u0e48\u0e32\u0e27\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14<\/span>\n\t\t<\/span>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a55b82c elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"a55b82c\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;cd095be&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:null,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}]}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9be1b36\" data-id=\"9be1b36\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-df4678a uael-heading-align-center elementor-widget elementor-widget-uael-advanced-heading\" data-id=\"df4678a\" data-element_type=\"widget\" data-widget_type=\"uael-advanced-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"uael-module-content uael-heading-wrapper\">\n\t\t\t\t\t\t\n\t\t\t<h2 class=\"uael-heading\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-heading-text elementor-inline-editing uael-size--default\" data-elementor-setting-key=\"heading_title\" data-elementor-inline-editing-toolbar=\"basic\">\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23<\/span>\n\t\t\t\t\t\t\t<\/h2>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3fb686f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3fb686f\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;0ad3846&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:null,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-5dcd7d7\" data-id=\"5dcd7d7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-39a250b elementor-cta--skin-classic elementor-animated-content elementor-widget elementor-widget-call-to-action\" data-id=\"39a250b\" data-element_type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/elementor\/thumbs\/4048-q07h0zxtm8wrakdz0slp6tj99k5qs6eeqbo2pzu3ds.jpg);\" role=\"img\" aria-label=\"4048\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h2 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\t\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1b\u0e23\u0e34\u0e0d\u0e0d\u0e32\u0e15\u0e23\u0e35\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\t\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15 \u0e2a\u0e32\u0e02\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e14\u0e19\u0e15\u0e23\u0e35\u0e41\u0e25\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e2a\u0e21 (\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e43\u0e2b\u0e21\u0e48 \u0e1e.\u0e28. 2566) \u0e41\u0e25\u0e30 \u0e28\u0e34\u0e25\u0e1b\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e41\u0e25\u0e30\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15 \u0e2a\u0e32\u0e02\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e25\u0e30\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c (\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e43\u0e2b\u0e21\u0e48 \u0e1e.\u0e28.2567)\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item \">\n\t\t\t\t\t<a class=\"elementor-cta__button elementor-button elementor-size-\" href=\"https:\/\/imse.kmitl.ac.th\/th\/undergraduate-2023\/\">\n\t\t\t\t\t\t\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-b6acc1a\" data-id=\"b6acc1a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f7da64f elementor-cta--skin-classic elementor-animated-content elementor-widget elementor-widget-call-to-action\" data-id=\"f7da64f\" data-element_type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/elementor\/thumbs\/61675-q07h0zxtm8wrakdz0slp6tj99k5qs6eeqbo2pzu3ds.jpg);\" role=\"img\" aria-label=\"61675\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h2 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\t\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15\u0e28\u0e36\u0e01\u0e29\u0e32\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tMASTER OF ENGINEERING  PROGRAM\nIN ACOUSTICS AND MULTIMEDIA TECHNOLOGY\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item \">\n\t\t\t\t\t<a class=\"elementor-cta__button elementor-button elementor-size-\" href=\"https:\/\/imse.kmitl.ac.th\/th\/pr-master-degree\/\">\n\t\t\t\t\t\t\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-b80e91f\" data-id=\"b80e91f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e188d75 elementor-cta--skin-classic elementor-animated-content elementor-widget elementor-widget-call-to-action\" data-id=\"e188d75\" data-element_type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<a class=\"elementor-cta\" href=\"https:\/\/imse.kmitl.ac.th\/th\/%e0%b8%ab%e0%b8%a5%e0%b8%b1%e0%b8%81%e0%b8%aa%e0%b8%b9%e0%b8%95%e0%b8%a3%e0%b8%a3%e0%b8%b0%e0%b8%a2%e0%b8%b0%e0%b8%aa%e0%b8%b1%e0%b9%89%e0%b8%99\/\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/elementor\/thumbs\/2928-q07h0zxtm8wrakdz0slp6tj99k5qs6eeqbo2pzu3ds.jpg);\" role=\"img\" aria-label=\"2928\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h2 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\t\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e23\u0e30\u0e22\u0e30\u0e2a\u0e31\u0e49\u0e19\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item \">\n\t\t\t\t\t<span class=\"elementor-cta__button elementor-button elementor-size-\">\n\t\t\t\t\t\t\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e457ff6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e457ff6\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9970c66\" data-id=\"9970c66\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3859767 elementor-widget elementor-widget-heading\" data-id=\"3859767\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0e15\u0e32\u0e23\u0e32\u0e07\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5a45314 elementor-widget elementor-widget-the-events-calendar-addon\" data-id=\"5a45314\" data-element_type=\"widget\" data-widget_type=\"the-events-calendar-addon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ectbe-calendar-wrapper\"><div class=\"ectbe_calendar_events_spinner\"><img decoding=\"async\" src=\"https:\/\/imse.kmitl.ac.th\/wp-content\/plugins\/events-widgets-for-elementor-and-the-events-calendar\/assets\/images\/ectbe-preloader.gif\"><\/div><div id=\"ectbe-event-calendar-5a45314\" class=\"ectbe-event-calendar-cls\" data-cal_id=\"5a45314\" data-locale=\"th\" data-defaultview=\"dayGridMonth\" data-first_day=\"0\" data-daterange=\"\" data-rangestart=\"\" data-rangeend=\"\" data-max_events=\"\" data-ev_category=\"[&quot;all&quot;]\" data-textcolor=\"#ffffff\" data-color=\"#5725ff\"><\/div><div id=\"ectbe-popup-wraper\" class=\"ectbe-modal ectbe-zoom-in\">\n            <div class=\"ectbe-ec-modal-bg\"><\/div>\n            <div class=\"ectbe-modal-content\">\n                <div class=\"ectbe-featured-img\"><\/div>\n                <div class=\"ectbe-modal-header\">                    \n                    <div class=\"ectbe-modal-close\"><span>X<\/span><\/div>\n                    <h2 class=\"ectbe-ec-modal-title\"><\/h2>\n                    <span class=\"ectbe-event-date-start ectbe-event-popup-date\"><\/span>\n                    <span class=\"ectbe-event-date-end ectbe-event-popup-date\"><\/span>\n                <\/div>\n                <div class=\"ectbe-modal-body\">\n                    <span class=\"ectbe-cost\"><\/span>\n                    <p><\/p>\n                <\/div><div class=\"ectbe-modal-footer\">\n                        <a class=\"ectbe-event-details-link\"><button>Read More<\/button><\/a>\n                    <\/div><\/div>\n        <\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2850998 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2850998\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;155a36d&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:null,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}]}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ab65f65\" data-id=\"ab65f65\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0e7c531 uael-heading-align-center elementor-widget elementor-widget-uael-advanced-heading\" data-id=\"0e7c531\" data-element_type=\"widget\" data-widget_type=\"uael-advanced-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"uael-module-content uael-heading-wrapper\">\n\t\t\t\t\t\t\n\t\t\t<h2 class=\"uael-heading\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-heading-text elementor-inline-editing uael-size--default\" data-elementor-setting-key=\"heading_title\" data-elementor-inline-editing-toolbar=\"basic\">Media<\/span>\n\t\t\t\t\t\t\t<\/h2>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a76f560 elementor-skin-carousel elementor-arrows-yes elementor-pagination-type-bullets elementor-pagination-position-outside elementor-widget elementor-widget-media-carousel\" data-id=\"a76f560\" data-element_type=\"widget\" data-settings=\"{&quot;slides_per_view&quot;:&quot;2&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;skin&quot;:&quot;carousel&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;show_arrows&quot;:&quot;yes&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;speed&quot;:500,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;loop&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]}}\" data-widget_type=\"media-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slides\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2020\/04\/\u0e04\u0e19\u0e44\u0e17\u0e22\u0e40\u0e23\u0e32\u0e23\u0e31\u0e01\u0e01\u0e31\u0e19-1.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"a76f560\" data-elementor-lightbox-title=\"\u0e04\u0e19\u0e44\u0e17\u0e22\u0e40\u0e23\u0e32\u0e23\u0e31\u0e01\u0e01\u0e31\u0e19\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjAyMiwidXJsIjoiaHR0cHM6XC9cL2ltc2Uua21pdGwuYWMudGhcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjBcLzA0XC9cdTBlMDRcdTBlMTlcdTBlNDRcdTBlMTdcdTBlMjJcdTBlNDBcdTBlMjNcdTBlMzJcdTBlMjNcdTBlMzFcdTBlMDFcdTBlMDFcdTBlMzFcdTBlMTktMS5qcGciLCJzbGlkZXNob3ciOiJhNzZmNTYwIn0%3D\" data-elementor-lightbox-video=\"https:\/\/www.youtube.com\/embed\/m59HXK6Wmy8?feature=oembed&amp;autoplay=1&amp;rel=0&amp;controls=0\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"\u0e04\u0e19\u0e44\u0e17\u0e22\u0e40\u0e23\u0e32\u0e23\u0e31\u0e01\u0e01\u0e31\u0e19\" style=\"background-image: url(&#039;https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2020\/04\/\u0e04\u0e19\u0e44\u0e17\u0e22\u0e40\u0e23\u0e32\u0e23\u0e31\u0e01\u0e01\u0e31\u0e19-1.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed-play\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-play\"><\/i>\t\t\t\t\t<span class=\"elementor-screen-only\">Play<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2020\/11\/\u0e2d\u0e38\u0e49\u0e21.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"a76f560\" data-elementor-lightbox-title=\"\u0e2d\u0e38\u0e49\u0e21\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjQ0NCwidXJsIjoiaHR0cHM6XC9cL2ltc2Uua21pdGwuYWMudGhcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjBcLzExXC9cdTBlMmRcdTBlMzhcdTBlNDlcdTBlMjEuanBnIiwic2xpZGVzaG93IjoiYTc2ZjU2MCJ9\" data-elementor-lightbox-video=\"https:\/\/www.youtube.com\/embed\/9QSebAvxJ-c?feature=oembed&amp;autoplay=1&amp;rel=0&amp;controls=0\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"\u0e2d\u0e38\u0e49\u0e21\" style=\"background-image: url(&#039;https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2020\/11\/\u0e2d\u0e38\u0e49\u0e21.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed-play\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-play\"><\/i>\t\t\t\t\t<span class=\"elementor-screen-only\">Play<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2025\/11\/151830232_3904719596255963_2593494895849500721_n.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"a76f560\" data-elementor-lightbox-title=\"151830232_3904719596255963_2593494895849500721_n\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzE0MTM4LCJ1cmwiOiJodHRwczpcL1wvaW1zZS5rbWl0bC5hYy50aFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMTFcLzE1MTgzMDIzMl8zOTA0NzE5NTk2MjU1OTYzXzI1OTM0OTQ4OTU4NDk1MDA3MjFfbi5qcGciLCJzbGlkZXNob3ciOiJhNzZmNTYwIn0%3D\" data-elementor-lightbox-video=\"https:\/\/www.youtube.com\/embed\/87BNZJ_KYoc?feature=oembed&amp;autoplay=1&amp;rel=0&amp;controls=0\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"151830232_3904719596255963_2593494895849500721_n\" style=\"background-image: url(&#039;https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2025\/11\/151830232_3904719596255963_2593494895849500721_n.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed-play\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-play\"><\/i>\t\t\t\t\t<span class=\"elementor-screen-only\">Play<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Previous\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Next\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8d91c84 elementor-skin-carousel elementor-arrows-yes elementor-pagination-type-bullets elementor-pagination-position-outside elementor-widget elementor-widget-media-carousel\" data-id=\"8d91c84\" data-element_type=\"widget\" data-settings=\"{&quot;slides_per_view&quot;:&quot;3&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;skin&quot;:&quot;carousel&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;show_arrows&quot;:&quot;yes&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;speed&quot;:500,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;loop&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]}}\" data-widget_type=\"media-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slides\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2020\/01\/m01.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"8d91c84\" data-elementor-lightbox-title=\"m01\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NzM4LCJ1cmwiOiJodHRwczpcL1wvaW1zZS5rbWl0bC5hYy50aFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMFwvMDFcL20wMS5qcGciLCJzbGlkZXNob3ciOiI4ZDkxYzg0In0%3D\" data-elementor-lightbox-video=\"https:\/\/www.youtube.com\/embed\/RBddJnpAXno?feature=oembed&amp;autoplay=1&amp;rel=0&amp;controls=0\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"m01\" style=\"background-image: url(&#039;https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2020\/01\/m01.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed-play\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-play\"><\/i>\t\t\t\t\t<span class=\"elementor-screen-only\">Play<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2020\/01\/m02.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"8d91c84\" data-elementor-lightbox-title=\"m02\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NzM5LCJ1cmwiOiJodHRwczpcL1wvaW1zZS5rbWl0bC5hYy50aFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMFwvMDFcL20wMi5qcGciLCJzbGlkZXNob3ciOiI4ZDkxYzg0In0%3D\" data-elementor-lightbox-video=\"https:\/\/www.youtube.com\/embed\/UGQ_kUGEoo8?feature=oembed&amp;autoplay=1&amp;rel=0&amp;controls=0\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"m02\" style=\"background-image: url(&#039;https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2020\/01\/m02.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed-play\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-play\"><\/i>\t\t\t\t\t<span class=\"elementor-screen-only\">Play<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2020\/01\/m03.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"8d91c84\" data-elementor-lightbox-title=\"m03\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NzQwLCJ1cmwiOiJodHRwczpcL1wvaW1zZS5rbWl0bC5hYy50aFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMFwvMDFcL20wMy5qcGciLCJzbGlkZXNob3ciOiI4ZDkxYzg0In0%3D\" data-elementor-lightbox-video=\"https:\/\/www.youtube.com\/embed\/5SYxk8CMluY?feature=oembed&amp;autoplay=1&amp;rel=0&amp;controls=0\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"m03\" style=\"background-image: url(&#039;https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2020\/01\/m03.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed-play\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-play\"><\/i>\t\t\t\t\t<span class=\"elementor-screen-only\">Play<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2025\/11\/maxresdefault.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"8d91c84\" data-elementor-lightbox-title=\"maxresdefault\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzE0MTM5LCJ1cmwiOiJodHRwczpcL1wvaW1zZS5rbWl0bC5hYy50aFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMTFcL21heHJlc2RlZmF1bHQuanBnIiwic2xpZGVzaG93IjoiOGQ5MWM4NCJ9\" data-elementor-lightbox-video=\"https:\/\/www.youtube.com\/embed\/KbG2CvHbfxw?feature=oembed&amp;autoplay=1&amp;rel=0&amp;controls=0\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"maxresdefault\" style=\"background-image: url(&#039;https:\/\/imse.kmitl.ac.th\/wp-content\/uploads\/2025\/11\/maxresdefault.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed-play\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-play\"><\/i>\t\t\t\t\t<span class=\"elementor-screen-only\">Play<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Previous\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Next\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-06024e5 uael-button-halign-center uael-button-stack-none elementor-widget elementor-widget-uael-buttons\" data-id=\"06024e5\" data-element_type=\"widget\" data-widget_type=\"uael-buttons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"uael-dual-button-outer-wrap\">\n\t\t\t<div class=\"uael-dual-button-wrap\">\n\t\t\t\t\t\t\t\t<div class=\"uael-button-wrapper uael-dual-button elementor-widget-button elementor-repeater-item-b7e8120 uael-dual-button-0\">\n\t\t\t\t\t<a class=\"elementor-button-link elementor-button elementor-size-lg elementor-button-link\" href=\"https:\/\/www.youtube.com\/channel\/UCPL0hh9hEkG6fXe1FUkKAoA\" target=\"_blank\">\n\t\t\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper uael-buttons-icon-\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-align-icon- elementor-button-icon\">\n\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text elementor-inline-editing\" data-elementor-setting-key=\"buttons.0.text\" data-elementor-inline-editing-toolbar=\"none\">\u0e14\u0e39\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21<\/span>\n\t\t<\/span>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ce66a08 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ce66a08\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-dd6fcc2\" data-id=\"dd6fcc2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cf53bdb elementor-widget elementor-widget-heading\" data-id=\"cf53bdb\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.kmitl.ac.th\/th\/procurement\" target=\"_blank\">\ud83d\udc49 \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d\u0e08\u0e31\u0e14\u0e08\u0e49\u0e32\u0e07 :\u00a0https:\/\/www.kmitl.ac.th\/th\/procurement \ud83d\udc48<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-11bd460 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"11bd460\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-bf95f43\" data-id=\"bf95f43\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-905cd07 elementor-widget elementor-widget-heading\" data-id=\"905cd07\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/council.kmitl.ac.th\/appeal\/\" target=\"_blank\">\ud83d\udc49 \u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e23\u0e49\u0e2d\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e38\u0e08\u0e23\u0e34\u0e15\u0e02\u0e2d\u0e07\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19 \u0e04\u0e25\u0e34\u0e01\u0e17\u0e35\u0e48\u0e19\u0e35\u0e49 \ud83d\udc48<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8183840 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8183840\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-2437da7\" data-id=\"2437da7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ccfb38f elementor-widget elementor-widget-heading\" data-id=\"ccfb38f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/mail.google.com\/mail\/?view=cm&#038;fs=1&#038;to=imsedirect@kmitl.ac.th\" target=\"_blank\">\ud83d\udc49 \u0e41\u0e08\u0e49\u0e07\u0e1b\u0e31\u0e0d\u0e2b\u0e32 \u0e2b\u0e23\u0e37\u0e2d\u0e23\u0e49\u0e2d\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e42\u0e14\u0e22\u0e15\u0e23\u0e07 :&nbsp;imsedirect@kmitl.ac.th \ud83d\udc48<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Click HereClick HereNo Gift PolicyClick Here\u0e2a\u0e31\u0e21\u0e20\u0e32\u0e29\u0e13\u0e4c\u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e02\u0e08\u0e23\u0e28\u0e31\u0e01\u0e14\u0e34\u0e4cCity [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"footnotes":"","_tec_slr_enabled":"","_tec_slr_layout":""},"class_list":["post-313749","page","type-page","status-publish","hentry"],"ticketed":false,"_links":{"self":[{"href":"https:\/\/imse.kmitl.ac.th\/th\/wp-json\/wp\/v2\/pages\/313749","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imse.kmitl.ac.th\/th\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/imse.kmitl.ac.th\/th\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/imse.kmitl.ac.th\/th\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/imse.kmitl.ac.th\/th\/wp-json\/wp\/v2\/comments?post=313749"}],"version-history":[{"count":121,"href":"https:\/\/imse.kmitl.ac.th\/th\/wp-json\/wp\/v2\/pages\/313749\/revisions"}],"predecessor-version":[{"id":314760,"href":"https:\/\/imse.kmitl.ac.th\/th\/wp-json\/wp\/v2\/pages\/313749\/revisions\/314760"}],"wp:attachment":[{"href":"https:\/\/imse.kmitl.ac.th\/th\/wp-json\/wp\/v2\/media?parent=313749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}